
{"id":485,"date":"2024-12-17T19:48:36","date_gmt":"2024-12-17T19:48:36","guid":{"rendered":"https:\/\/www.delivrexgo.com\/?page_id=485"},"modified":"2025-12-23T12:11:14","modified_gmt":"2025-12-23T12:11:14","slug":"manual-del-usuario","status":"publish","type":"page","link":"https:\/\/www.delivrexgo.com\/es\/manual-del-usuario\/","title":{"rendered":"Manual del usuario"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"485\" class=\"elementor elementor-485\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5760f9f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5760f9f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e832b76\" data-id=\"1e832b76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f4c9eb8 elementor-widget elementor-widget-heading\" data-id=\"3f4c9eb8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manual del usuario  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-661f0c3d elementor-widget elementor-widget-spacer\" data-id=\"661f0c3d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-131610f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"131610f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-530db13d\" data-id=\"530db13d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6039bbf elementor-widget elementor-widget-shortcode\" data-id=\"6039bbf\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n\n<div\n\tclass=\"betterdocs-category-grid-wrapper betterdocs-shortcode\">\n\t<div\n\t\tclass=\"betterdocs-category-grid-inner-wrapper layout-1 masonry docs-col-3 single-kb\" data-column_desktop=\"3\" style=\"--column: 3;\">\n\t\t\n<article\n\tdata-id=\"25\" class=\"betterdocs-single-category-wrapper category-grid default\">\n\t<div class=\"betterdocs-single-category-inner\">\n\t\t\n<div class=\"betterdocs-category-header\">\n\t<div class=\"betterdocs-category-header-inner\">\n\t\t\n<div class=\"betterdocs-category-icon\">\n\t<img decoding=\"async\" alt=\"\" class=\"betterdocs-category-icon-img\" src=\"https:\/\/www.delivrexgo.com\/wp-content\/uploads\/2024\/12\/sinscrire-150x150-1.png\" \/><\/div>\n<h2 class=\"betterdocs-category-title\">Inscripci\u00f3n<\/h2>\n<div data-count=\"6\" class=\"betterdocs-category-items-counts\">\n\t<span>\n\t\t 6 \t<\/span>\n<\/div>\n\t<\/div>\n<\/div>\n<div class=\"betterdocs-body\">\n<ul class=\"betterdocs-articles-list\">\n\t<li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/crear-una-cuenta\/\"><span>Crear una cuenta :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/pantalla-mi-cuenta\/\"><span>Pantalla \u00ab Mi cuenta \u00bb<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/elimine-su-cuenta\/\"><span>Elimine su cuenta :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/modificar-sus-datos-personales\/\"><span>Modificar sus datos personales :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/enviar-una-sugerencia-o-reclamacion\/\"><span>Enviar una sugerencia o reclamaci\u00f3n :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/vea-los-anuncios-incompletos-y-publicados-y-las-transacciones-en-curso-y-completadas\/\"><span>Vea los anuncios incompletos y publicados y las transacciones en curso y completadas:<\/span> <\/a><\/li><\/ul>\n<\/div>\t<\/div>\n<\/article>\n\n<article\n\tdata-id=\"26\" class=\"betterdocs-single-category-wrapper category-grid default\">\n\t<div class=\"betterdocs-single-category-inner\">\n\t\t\n<div class=\"betterdocs-category-header\">\n\t<div class=\"betterdocs-category-header-inner\">\n\t\t\n<div class=\"betterdocs-category-icon\">\n\t<img decoding=\"async\" alt=\"\" class=\"betterdocs-category-icon-img\" src=\"https:\/\/www.delivrexgo.com\/wp-content\/uploads\/2024\/12\/bon-de-commande-150x150-1.png\" \/><\/div>\n<h2 class=\"betterdocs-category-title\">Pedir<\/h2>\n<div data-count=\"12\" class=\"betterdocs-category-items-counts\">\n\t<span>\n\t\t 12 \t<\/span>\n<\/div>\n\t<\/div>\n<\/div>\n<div class=\"betterdocs-body\">\n<ul class=\"betterdocs-articles-list\">\n\t<li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/menu-principal\/\"><span>Men\u00fa principal :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/descripcion-del-producto-o-productos\/\"><span>Descripci\u00f3n del producto o productos:<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/introduzca-la-comision-y-la-fecha-de-entrega\/\"><span>Introduzca la comisi\u00f3n y la fecha de entrega:<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/resumen-de-anuncio-y-pago\/\"><span>Resumen de anuncio y pago :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/sugerencia-de-modificacion-del-anuncio\/\"><span>Sugerencia de modificaci\u00f3n del anuncio :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/aceptacion-o-rechazo-de-las-propuestas-de-modificacion-del-anuncio\/\"><span>Aceptaci\u00f3n o rechazo de las propuestas de modificaci\u00f3n del anuncio :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/aceptacion-de-su-anuncio-por-un-repartidor-transaccion-en-curso\/\"><span>Aceptaci\u00f3n de su anuncio por un repartidor (Transacci\u00f3n en curso) :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/envio-y-recepcion-de-mensajes-entre-usted-y-el-repartidor\/\"><span>Env\u00edo y recepci\u00f3n de mensajes entre usted y el repartidor :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/validar-y-finalizar-la-transaccion\/\"><span>Validar y finalizar la transacci\u00f3n :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/la-fecha-de-entrega-prevista-ha-pasado-y-la-transaccion-no-ha-finalizado\/\"><span>La fecha de entrega prevista ha pasado y la transacci\u00f3n no ha finalizado:<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/el-plazo-de-entrega-ha-vencido-y-la-transaccion-no-ha-finalizado\/\"><span>El plazo de entrega ha vencido y la transacci\u00f3n no ha finalizado:<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/evaluacion\/\"><span>Evaluaci\u00f3n :<\/span> <\/a><\/li><\/ul>\n<\/div>\t<\/div>\n<\/article>\n\n<article\n\tdata-id=\"27\" class=\"betterdocs-single-category-wrapper category-grid default\">\n\t<div class=\"betterdocs-single-category-inner\">\n\t\t\n<div class=\"betterdocs-category-header\">\n\t<div class=\"betterdocs-category-header-inner\">\n\t\t\n<div class=\"betterdocs-category-icon\">\n\t<img decoding=\"async\" alt=\"\" class=\"betterdocs-category-icon-img\" src=\"https:\/\/www.delivrexgo.com\/wp-content\/uploads\/2024\/12\/livraison-de-colis-150x150-1.png\" \/><\/div>\n<h2 class=\"betterdocs-category-title\">Entrega<\/h2>\n<div data-count=\"11\" class=\"betterdocs-category-items-counts\">\n\t<span>\n\t\t 11 \t<\/span>\n<\/div>\n\t<\/div>\n<\/div>\n<div class=\"betterdocs-body\">\n<ul class=\"betterdocs-articles-list\">\n\t<li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/menu-principal-2\/\"><span>Men\u00fa principal :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/su-destino\/\"><span>Su destino :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/anuncios-del-solicitante-beneficiario\/\"><span>Anuncios del solicitante (beneficiario) :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/clasificacion-de-los-anuncios\/\"><span>Clasificaci\u00f3n de los anuncios :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/resumen-del-anuncio\/\"><span>Resumen del anuncio :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/operaciones-en-curso\/\"><span>Operaciones en curso :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/enviar-y-recibir-mensajes-entre-usted-y-el-destinatario\/\"><span>Enviar y recibir mensajes entre usted y el destinatario :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/validar-y-finalizar-la-transaccion-2\/\"><span>Validar y finalizar la transacci\u00f3n :<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/la-fecha-de-entrega-prevista-ha-pasado-y-la-transaccion-no-ha-finalizado-2\/\"><span>La fecha de entrega prevista ha pasado y la transacci\u00f3n no ha finalizado:<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/el-plazo-de-entrega-ha-vencido-y-la-transaccion-no-ha-finalizado-2\/\"><span>El plazo de entrega ha vencido y la transacci\u00f3n no ha finalizado:<\/span> <\/a><\/li><li><svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n\t viewBox=\"0 0 100 100\" xml:space=\"preserve\">\n<g id=\"Icon\">\n\t<path class=\"st0\" d=\"M90.6,87c0,3.4-1.3,6.6-3.7,9c-2.4,2.4-5.6,3.7-9,3.7H22.5c-3.4,0-6.6-1.3-9-3.7c-2.4-2.4-3.7-5.6-3.7-9V13.1\n\t\tc0-3.4,1.3-6.6,3.7-9c2.4-2.4,5.6-3.7,9-3.7h39.7c2.1,0,4.2,0.8,5.7,2.4l20.4,20.4c1.5,1.5,2.4,3.6,2.4,5.7V87z M83.7,87V28.9\n\t\tc0-0.3-0.1-0.6-0.3-0.8L62.9,7.7c-0.2-0.2-0.5-0.3-0.8-0.3H22.5c-1.5,0-3,0.6-4.1,1.7c-1.1,1.1-1.7,2.5-1.7,4.1V87\n\t\tc0,1.5,0.6,3,1.7,4.1c1.1,1.1,2.5,1.7,4.1,1.7h55.4c1.5,0,3-0.6,4.1-1.7C83.1,90,83.7,88.6,83.7,87z\"\/>\n\t<path class=\"st0\" d=\"M60.6,6.2c0-1.9,1.6-3.5,3.5-3.5s3.5,1.6,3.5,3.5v16.2c0,0.6,0.5,1.2,1.2,1.2h16.2c1.9,0,3.5,1.6,3.5,3.5\n\t\ts-1.6,3.5-3.5,3.5H68.7c-4.5,0-8.1-3.6-8.1-8.1V6.2z\"\/>\n\t<path class=\"st0\" d=\"M31.7,46.6c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,62.8c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h36.9c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n\t<path class=\"st0\" d=\"M31.7,79c-1.9,0-3.5-1.6-3.5-3.5c0-1.9,1.6-3.5,3.5-3.5h20.8c1.9,0,3.5,1.6,3.5,3.5c0,1.9-1.6,3.5-3.5,3.5\n\t\tH31.7z\"\/>\n<\/g>\n<\/svg>\n<a href=\"https:\/\/www.delivrexgo.com\/es\/docs\/evaluacion-2\/\"><span>Evaluaci\u00f3n :<\/span> <\/a><\/li><\/ul>\n<\/div>\t<\/div>\n<\/article>\n\t<\/div>\n\t\t<div class=\"clearfix\"><\/div>\n\t<\/div>\n\n\n\n\n\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3659a8c elementor-widget elementor-widget-shortcode\" data-id=\"3659a8c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div\n\tclass=\"betterdocs-category-grid-wrapper betterdocs-shortcode\">\n\t<div\n\t\tclass=\"betterdocs-category-grid-inner-wrapper layout-1 masonry docs-col-3 single-kb\" data-column_desktop=\"3\" style=\"--column: 3;\">\n\t\t\t<\/div>\n\t\t<div class=\"clearfix\"><\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Manual del usuario<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-485","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/pages\/485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/comments?post=485"}],"version-history":[{"count":17,"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/pages\/485\/revisions"}],"predecessor-version":[{"id":809,"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/pages\/485\/revisions\/809"}],"wp:attachment":[{"href":"https:\/\/www.delivrexgo.com\/es\/wp-json\/wp\/v2\/media?parent=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}